{"id":683,"date":"2020-01-07T07:51:38","date_gmt":"2020-01-07T03:21:38","guid":{"rendered":"http:\/\/batteriamercato.com\/blog\/?p=683"},"modified":"2020-01-07T07:51:38","modified_gmt":"2020-01-07T03:21:38","slug":"apple-prima-nel-settore-degli-auricolari-true-wireless","status":"publish","type":"post","link":"https:\/\/www.batteriamercato.com\/blog\/index.php\/2020\/01\/07\/apple-prima-nel-settore-degli-auricolari-true-wireless\/","title":{"rendered":"Apple prima nel settore degli auricolari true wireless"},"content":{"rendered":"\n<p>\n\nAuricolari e cuffie senza fili sono tra i gadget tecnologici del momento. Ma anche i dispositivi indossabili pi\u00f9 popolari, davanti a smartwach e bracciali da fitness. Da luglio a settembre ne sono stati venduti 96,7 milioni di unit\u00e0 a livello mondiale (+53% su base annua), e nel quarto trimestre &#8211; complici gli acquisti natalizi &#8211; dovrebbero aver superato traguardo dei 100 milioni di unit\u00e0.<\/p>\n\n\n\n<p>A fornire i dati sono i ricercatori di Canalys, secondo i quali, per ogni cento smartphone immessi in commercio nel terzo trimestre, sono stati consegnati 27 auricolari\/cuffie e 13 smartwatch\/smartband. A trainare il settore sono gli auricolari &#8220;true wireless\u201d (completamente senza fili) come gli AirPods di Apple. Il segmento \u00e8 infatti cresciuto del 183% a quota 43 milioni di unit\u00e0. E Apple, con 18,2 milioni di AirPods consegnati nel terzo trimestre, ne detiene il 43%. Gli auricolari wireless tradizionali sono il secondo segmento con 32 milioni di unit\u00e0 commercializzate (+6%). L&#8217;azienda leader \u00e8 Jbl, seguita da Sony e Skullcandy. Al terzo posto le cuffie wireless, con 22 milioni di dispositivi (+22%). Anche qui \u00e8 in testa Jbl, davanti a Sony e Bose.<\/p>\n\n\n\n<p>&gt;&gt;&gt;&gt;&gt;&gt;&gt;&gt;&gt;&gt;&gt;<a href=\"http:\/\/www.batteriamercato.com\/plantronics-batteria-CS540-p180727.htm\">Plantronics CS540 CS540A CO54 C054 Batteria del CS540<\/a><br>&gt;&gt;&gt;&gt;&gt;&gt;&gt;&gt;&gt;&gt;&gt;<a href=\"http:\/\/www.batteriamercato.com\/varta-batteria-CP1654_A3-p180225.htm\">VARTA CP1654 A3 Bluetoot Headset Batteria del CP1654_A3<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"mh-excerpt\"><p>Auricolari e cuffie senza fili sono tra i gadget tecnologici del momento. Ma anche i dispositivi indossabili pi\u00f9 popolari, davanti a smartwach e bracciali da <a class=\"mh-excerpt-more\" href=\"https:\/\/www.batteriamercato.com\/blog\/index.php\/2020\/01\/07\/apple-prima-nel-settore-degli-auricolari-true-wireless\/\" title=\"Apple prima nel settore degli auricolari true wireless\">[&#8230;]<\/a><\/p>\n<\/div>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[7],"tags":[],"_links":{"self":[{"href":"https:\/\/www.batteriamercato.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/683"}],"collection":[{"href":"https:\/\/www.batteriamercato.com\/blog\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.batteriamercato.com\/blog\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.batteriamercato.com\/blog\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.batteriamercato.com\/blog\/index.php\/wp-json\/wp\/v2\/comments?post=683"}],"version-history":[{"count":1,"href":"https:\/\/www.batteriamercato.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/683\/revisions"}],"predecessor-version":[{"id":684,"href":"https:\/\/www.batteriamercato.com\/blog\/index.php\/wp-json\/wp\/v2\/posts\/683\/revisions\/684"}],"wp:attachment":[{"href":"https:\/\/www.batteriamercato.com\/blog\/index.php\/wp-json\/wp\/v2\/media?parent=683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.batteriamercato.com\/blog\/index.php\/wp-json\/wp\/v2\/categories?post=683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.batteriamercato.com\/blog\/index.php\/wp-json\/wp\/v2\/tags?post=683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}